{"id":13,"date":"2024-04-29T07:41:53","date_gmt":"2024-04-29T07:41:53","guid":{"rendered":"https:\/\/cristovelazquez.rkinformatika.online\/?page_id=13"},"modified":"2026-06-09T20:36:50","modified_gmt":"2026-06-09T19:36:50","slug":"quienes-somos","status":"publish","type":"page","link":"https:\/\/cristovelazquez.com\/eu\/quienes-somos\/","title":{"rendered":"Quienes Somos"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"13\" class=\"elementor elementor-13\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d51967 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0d51967\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2d4aec\" data-id=\"b2d4aec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-231fa9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"231fa9f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;pyramids&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M761.9,44.1L643.1,27.2L333.8,98L0,3.8V0l1000,0v3.9\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6614226\" data-id=\"6614226\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45b8b02 elementor-widget elementor-widget-heading\" data-id=\"45b8b02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra Historia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-215854a elementor-widget elementor-widget-image\" data-id=\"215854a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1152\" height=\"2048\" src=\"https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-1152x2048.jpeg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-3402\" alt=\"\" srcset=\"https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-1152x2048.jpeg 1152w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-169x300.jpeg 169w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-576x1024.jpeg 576w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-768x1365.jpeg 768w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-864x1536.jpeg 864w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-7x12.jpeg 7w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-1320x2346.jpeg 1320w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-14x24.jpeg 14w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-20x36.jpeg 20w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-27x48.jpeg 27w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-600x1066.jpeg 600w, https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-scaled.jpeg 1440w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-01fc46c\" data-id=\"01fc46c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e8a5c1 elementor-widget elementor-widget-text-editor\" data-id=\"2e8a5c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tempus by Cristo Vel\u00e1zquez es mucho m\u00e1s que una marca de complementos; es la historia de un legado familiar convertido en creatividad, dise\u00f1o y artesan\u00eda.<\/p><p>La palabra Tempus, que en lat\u00edn significa tiempo, representa la esencia de nuestra marca y el camino que nos ha tra\u00eddo hasta aqu\u00ed. Es la uni\u00f3n de tres tiempos que forman parte de nuestra historia y que hoy viven en cada una de nuestras creaciones.<\/p><p>El primero es el pasado, representado por mi abuela, modista, artesana del ganchillo y conocedora de numerosos oficios tradicionales. De ella hered\u00e9 el respeto por la artesan\u00eda, el amor por los detalles y la convicci\u00f3n de que las manos son capaces de transformar los materiales m\u00e1s sencillos en piezas llenas de valor y significado.<\/p><p>El segundo es el presente, representado por mi madre, modista de profesi\u00f3n durante toda su vida. Su dedicaci\u00f3n, esfuerzo y pasi\u00f3n por el oficio me ense\u00f1aron que la calidad no es una meta, sino una forma de trabajar y de entender la vida. Su ejemplo sigue siendo una fuente constante de inspiraci\u00f3n.<\/p><p>El tercero es el futuro, que represento a trav\u00e9s de Tempus. En cada dise\u00f1o fusiono las ense\u00f1anzas de ambas generaciones con mi propia visi\u00f3n creativa, uniendo confecci\u00f3n, artesan\u00eda y dise\u00f1o contempor\u00e1neo para crear piezas con identidad propia. Cada creaci\u00f3n es un puente entre la tradici\u00f3n y la innovaci\u00f3n, entre la historia que nos precede y el camino que a\u00fan est\u00e1 por recorrer.<\/p><p>Desde Canarias, elaboramos piezas que nacen del tiempo, de la dedicaci\u00f3n y del respeto por el trabajo bien hecho. Creemos en la artesan\u00eda como una forma de expresi\u00f3n, en la calidad como un compromiso y en la creatividad como la mejor manera de mantener vivo un legado.<\/p><p>Porque Tempus no es solo una marca. Es una historia familiar hecha a mano. Es pasado, presente y futuro unidos en una misma creaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ff058b5 e-flex e-con-boxed e-con e-parent\" data-id=\"ff058b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a314a49 e-con-full e-flex e-con e-child\" data-id=\"a314a49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1464250 elementor-widget elementor-widget-heading\" data-id=\"1464250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfTienes una tienda y quieres vender Tempus by Cristo Vel\u00e1zquez?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d370a9f elementor-widget elementor-widget-text-editor\" data-id=\"d370a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Si est\u00e1s interesad@ en incorporar algunos de los productos fabricados por Tempus by Cristo Vel\u00e1zquez en tu tienda f\u00edsica, ponte en contacto con nosotros y te explicaremos como hacerlo, utiliza el formulario de <span style=\"color: #993300;\"><a style=\"color: #993300;\" href=\"https:\/\/cristovelazquez.com\/eu\/trabaja-con-nosotros\/\" data-wplink-edit=\"true\">contacto<\/a><\/span> para enviar la solicitud.<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nuestra Historia Tempus by Cristo Vel\u00e1zquez es mucho m\u00e1s que una marca de complementos; es la historia de un legado familiar convertido en creatividad, dise\u00f1o y artesan\u00eda. La palabra Tempus, que en lat\u00edn significa tiempo, representa la esencia de nuestra marca y el camino que nos ha tra\u00eddo hasta aqu\u00ed. Es la uni\u00f3n de tres [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quienes Somos - Tempus by Cristo Velazquez<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cristovelazquez.com\/eu\/quienes-somos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quienes Somos - Tempus by Cristo Velazquez\" \/>\n<meta property=\"og:description\" content=\"Nuestra Historia Tempus by Cristo Vel\u00e1zquez es mucho m\u00e1s que una marca de complementos; es la historia de un legado familiar convertido en creatividad, dise\u00f1o y artesan\u00eda. La palabra Tempus, que en lat\u00edn significa tiempo, representa la esencia de nuestra marca y el camino que nos ha tra\u00eddo hasta aqu\u00ed. Es la uni\u00f3n de tres [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cristovelazquez.com\/eu\/quienes-somos\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempus by Cristo Velazquez\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T19:36:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/quienes-somos\\\/\",\"url\":\"https:\\\/\\\/cristovelazquez.com\\\/quienes-somos\\\/\",\"name\":\"Quienes Somos - Tempus by Cristo Velazquez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/quienes-somos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/quienes-somos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cristovelazquez.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/DSC2668-1152x2048.jpeg\",\"datePublished\":\"2024-04-29T07:41:53+00:00\",\"dateModified\":\"2026-06-09T19:36:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/quienes-somos\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cristovelazquez.com\\\/quienes-somos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/quienes-somos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cristovelazquez.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/DSC2668-1152x2048.jpeg\",\"contentUrl\":\"https:\\\/\\\/cristovelazquez.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/DSC2668-1152x2048.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/quienes-somos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cristovelazquez.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quienes Somos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/#website\",\"url\":\"https:\\\/\\\/cristovelazquez.com\\\/\",\"name\":\"Tempus by Cristo Velazquez\",\"description\":\"Tempus by Cristo Velazquez\",\"publisher\":{\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cristovelazquez.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/#organization\",\"name\":\"Tempus by Cristo Velazquez\",\"url\":\"https:\\\/\\\/cristovelazquez.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cristovelazquez.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-Cristo-Velazquez-2026-VECTOR-scaled-e1787911259695.png\",\"contentUrl\":\"https:\\\/\\\/cristovelazquez.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-Cristo-Velazquez-2026-VECTOR-scaled-e1787911259695.png\",\"width\":350,\"height\":394,\"caption\":\"Tempus by Cristo Velazquez\"},\"image\":{\"@id\":\"https:\\\/\\\/cristovelazquez.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quienes Somos - Tempus by Cristo Velazquez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cristovelazquez.com\/eu\/quienes-somos\/","og_locale":"en_US","og_type":"article","og_title":"Quienes Somos - Tempus by Cristo Velazquez","og_description":"Nuestra Historia Tempus by Cristo Vel\u00e1zquez es mucho m\u00e1s que una marca de complementos; es la historia de un legado familiar convertido en creatividad, dise\u00f1o y artesan\u00eda. La palabra Tempus, que en lat\u00edn significa tiempo, representa la esencia de nuestra marca y el camino que nos ha tra\u00eddo hasta aqu\u00ed. Es la uni\u00f3n de tres [&hellip;]","og_url":"https:\/\/cristovelazquez.com\/eu\/quienes-somos\/","og_site_name":"Tempus by Cristo Velazquez","article_modified_time":"2026-06-09T19:36:50+00:00","og_image":[{"width":1440,"height":2560,"url":"https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cristovelazquez.com\/quienes-somos\/","url":"https:\/\/cristovelazquez.com\/quienes-somos\/","name":"Quienes Somos - Tempus by Cristo Velazquez","isPartOf":{"@id":"https:\/\/cristovelazquez.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cristovelazquez.com\/quienes-somos\/#primaryimage"},"image":{"@id":"https:\/\/cristovelazquez.com\/quienes-somos\/#primaryimage"},"thumbnailUrl":"https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-1152x2048.jpeg","datePublished":"2024-04-29T07:41:53+00:00","dateModified":"2026-06-09T19:36:50+00:00","breadcrumb":{"@id":"https:\/\/cristovelazquez.com\/quienes-somos\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cristovelazquez.com\/quienes-somos\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/cristovelazquez.com\/quienes-somos\/#primaryimage","url":"https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-1152x2048.jpeg","contentUrl":"https:\/\/cristovelazquez.com\/wp-content\/uploads\/2026\/06\/DSC2668-1152x2048.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cristovelazquez.com\/quienes-somos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cristovelazquez.com\/"},{"@type":"ListItem","position":2,"name":"Quienes Somos"}]},{"@type":"WebSite","@id":"https:\/\/cristovelazquez.com\/#website","url":"https:\/\/cristovelazquez.com\/","name":"Tempus by Cristo Velazquez","description":"Tempus by Cristo Velazquez","publisher":{"@id":"https:\/\/cristovelazquez.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cristovelazquez.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/cristovelazquez.com\/#organization","name":"Tempus by Cristo Velazquez","url":"https:\/\/cristovelazquez.com\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/cristovelazquez.com\/#\/schema\/logo\/image\/","url":"https:\/\/cristovelazquez.com\/wp-content\/uploads\/2024\/04\/Logo-Cristo-Velazquez-2026-VECTOR-scaled-e1787911259695.png","contentUrl":"https:\/\/cristovelazquez.com\/wp-content\/uploads\/2024\/04\/Logo-Cristo-Velazquez-2026-VECTOR-scaled-e1787911259695.png","width":350,"height":394,"caption":"Tempus by Cristo Velazquez"},"image":{"@id":"https:\/\/cristovelazquez.com\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cristovelazquez.com\/eu\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cristovelazquez.com\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cristovelazquez.com\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cristovelazquez.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cristovelazquez.com\/eu\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":200,"href":"https:\/\/cristovelazquez.com\/eu\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"predecessor-version":[{"id":3434,"href":"https:\/\/cristovelazquez.com\/eu\/wp-json\/wp\/v2\/pages\/13\/revisions\/3434"}],"wp:attachment":[{"href":"https:\/\/cristovelazquez.com\/eu\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}